{"id":1386,"date":"2026-05-13T11:02:29","date_gmt":"2026-05-13T09:02:29","guid":{"rendered":"https:\/\/lesquenouilles.fr\/?p=1386"},"modified":"2026-05-13T11:02:30","modified_gmt":"2026-05-13T09:02:30","slug":"algarve-2026-jour-4-journee-de-transition","status":"publish","type":"post","link":"https:\/\/lesquenouilles.fr\/index.php\/2026\/05\/13\/algarve-2026-jour-4-journee-de-transition\/","title":{"rendered":"Algarve 2026 : jour 4, journ\u00e9e de transition"},"content":{"rendered":"\n<p>Cette journ\u00e9e de mardi a \u00e9t\u00e9 un peu particuli\u00e8re, car la nuit a \u00e9t\u00e9 soucieuse et le sommeil perturb\u00e9. En effet, nous avions perdu tout contact avec la maison depuis la veille au soir aux alentours de 22h30 (heure Fran\u00e7aise).<\/p>\n\n\n\n<p>Impossible de savoir ce qui s&rsquo;\u00e9tait pass\u00e9 pour que la connexion soit ainsi coup\u00e9e.<\/p>\n\n\n\n<p>merci a Marine et Tanguy qui sont all\u00e9s inspecter la maison pour se rendre compte que le disjoncteur avait saut\u00e9 (pour qu&rsquo;elle raison ? Myst\u00e8re.)<\/p>\n\n\n\n<p>Finalement, on d\u00e9cide en d\u00e9but d&rsquo;apr\u00e8s midi d&rsquo;explorer la zone a l&rsquo;est d&rsquo;Albufeira.<\/p>\n\n\n\n<p>on s&rsquo;arr\u00eate a Quarteira, sorte de zone baln\u00e9aire avec ses grandes all\u00e9es pi\u00e9tonnes ou cyclistes bord\u00e9es de boutiques et de restaurants.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142627.jpeg\" alt=\"\" class=\"wp-image-1379\" srcset=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142627.jpeg 800w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142627-300x225.jpeg 300w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142627-768x576.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Les architectures sont moins typiques qu&rsquo;Albufeira, plus modernes mais plut\u00f4t ann\u00e9es 70..80 et donc moins modernes que Portimao.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142645.jpeg\" alt=\"\" class=\"wp-image-1384\" srcset=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142645.jpeg 800w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142645-300x225.jpeg 300w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_142645-768x576.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>On cherche ensuite a aller visiter un producteur d&rsquo;agrumes mais qu&rsquo;on ne trouvera jamais&#8230;dommage.<\/p>\n\n\n\n<p>En fin de journ\u00e9e, on d\u00e9cide une nouvelle exploration de Albufeira old town et on d\u00e9couvre une nouvelle partie qu&rsquo;on avait pas encore vue. La vieille ville est tr\u00e8s sympa, anim\u00e9e et festive mais beaucoup plus agr\u00e9able qu&rsquo;une autre partie de la ville beaucoup trop bruyante avec ses bars karaok\u00e9s et autres clubs fa\u00e7on Ibiza<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174731.jpeg\" alt=\"\" class=\"wp-image-1383\" srcset=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174731.jpeg 800w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174731-300x225.jpeg 300w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174731-768x576.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174836-768x1024.jpeg\" alt=\"\" class=\"wp-image-1382\" srcset=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174836-768x1024.jpeg 768w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174836-225x300.jpeg 225w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174836.jpeg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174926.jpeg\" alt=\"\" class=\"wp-image-1381\" srcset=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174926.jpeg 800w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174926-300x225.jpeg 300w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_174926-768x576.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_175947-768x1024.jpeg\" alt=\"\" class=\"wp-image-1380\" srcset=\"https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_175947-768x1024.jpeg 768w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_175947-225x300.jpeg 225w, https:\/\/lesquenouilles.fr\/wp-content\/uploads\/2026\/05\/IMG_20260512_175947.jpeg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette journ\u00e9e de mardi a \u00e9t\u00e9 un peu particuli\u00e8re, car la nuit a \u00e9t\u00e9 soucieuse et le sommeil perturb\u00e9. En effet, nous avions perdu tout contact avec la maison depuis la veille au soir aux alentours de 22h30 (heure Fran\u00e7aise). Impossible de savoir ce qui s&rsquo;\u00e9tait pass\u00e9 pour que la connexion soit ainsi coup\u00e9e. merci [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,4],"tags":[78,84,80,88],"class_list":["post-1386","post","type-post","status-publish","format-standard","hentry","category-77","category-voyages","tag-78","tag-albufeira","tag-algarve","tag-old-town","entry"],"_links":{"self":[{"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/posts\/1386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1386"}],"version-history":[{"count":1,"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/posts\/1386\/revisions"}],"predecessor-version":[{"id":1387,"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/posts\/1386\/revisions\/1387"}],"wp:attachment":[{"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lesquenouilles.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}